{"id":8356,"date":"2024-03-06T17:31:32","date_gmt":"2024-03-06T17:31:32","guid":{"rendered":"https:\/\/www.turbocrowd.it\/?p=8356"},"modified":"2025-05-22T10:38:21","modified_gmt":"2025-05-22T10:38:21","slug":"crowdfunding-substack-etude-de-cas","status":"publish","type":"post","link":"https:\/\/www.turbocrowd.it\/fr\/crowdfunding-substack-etude-de-cas\/","title":{"rendered":"Histoires \u00e0 succ\u00e8s : \u00e9tude de cas sur le crowdfunding de Substack"},"content":{"rendered":"<p class=\"translation-block\"><strong>Substack<\/strong> est une <a href=\"https:\/\/substack.com\/home-i\" target=\"_blank\" rel=\"noreferrer noopener\">plateforme am\u00e9ricaine<\/a> qui propose aux entreprises, aux \u00e9crivains et aux journalistes de publier gratuitement des lettres d'information et d'autres contenus et de gagner de l'argent en demandant aux lecteurs d'acheter un abonnement pour l'utiliser. Le portail conserve alors 10% provenant des abonnements des lecteurs. Il s'agit d'un mod\u00e8le d'entreprise bas\u00e9 sur l'inclusion, la m\u00e9ritocratie et la participation ascendante, ce qui explique \u00e9galement pourquoi il a voulu exp\u00e9rimenter le crowdfunding<\/strong> en tant que mode de financement.<\/p>\n\n\n\n<p class=\"translation-block\">L'\u00e9tude de cas <strong>Substack<\/strong> est toutefois int\u00e9ressante car elle montre \u00e0 quel point diff\u00e9rentes sources de financement peuvent convenir \u00e0 une start-up \u00e0 diff\u00e9rents stades de d\u00e9veloppement et dans diff\u00e9rentes situations historiques.<\/p>\n\n\n\n<p>Substack est n\u00e9 en 2017 et a rapidement rencontr\u00e9 le succ\u00e8s aupr\u00e8s des journalistes et pigistes de niche, qui peinent \u00e0 trouver un espace ailleurs, mais aussi aupr\u00e8s des professionnels confirm\u00e9s, \u00e0 la faveur de la crise croissante du mod\u00e8le d'information des journaux et de la fortune du mod\u00e8le \" parcellis\u00e9 \" de lecture et de fructification des m\u00e9dias. Plus tard, le mod\u00e8le s'est \u00e9tendu \u00e0 d'autres types de contenus, tels que les podcasts.<\/p>\n\n\n\n<p>Aujourd'hui, la plateforme compte plus de 35 millions d'abonnements actifs, dont 2 millions d'abonnements payants.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Du capital-risque au crowdfunding<\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"translation-block\">La croissance de Substack a \u00e9t\u00e9 tr\u00e8s rapide au cours de ses deux premi\u00e8res ann\u00e9es d'existence, mais l'entreprise avait besoin de fonds pour poursuivre et acc\u00e9l\u00e9rer son d\u00e9veloppement. Le <strong>mod\u00e8le \u00e9conomique<\/strong> de Substack a pos\u00e9 \u00e0 l'entreprise un probl\u00e8me \"\u00e9thique\" d\u00e9licat : la promesse de la plateforme est d'offrir une libert\u00e9 et une ind\u00e9pendance absolues aux auteurs et aux lecteurs, en \u00e9vitant l'implication des annonceurs qui finissent souvent par influencer l'orientation du contenu dans les m\u00e9dias pour lesquels ils sont la principale source de financement.<\/p>\n\n\n\n<p class=\"translation-block\">Le choix s'est port\u00e9 sur le Venture Capital: avec une promesse explicite aux utilisateurs de ne pas trahir ses principes de base, Substack a r\u00e9alis\u00e9 un premier tour de table en 2019 avec le fonds de capital-risque Andreessen Horowitz, levant plus de 15 millions de dollars.<\/p>\n\n\n\n<p class=\"translation-block\">Un deuxi\u00e8me tour de table avec le m\u00eame fonds en 2021 a permis \u00e0 Substack de r\u00e9colter 65 millions d'USD, portant la <a href=\"https:\/\/www.turbocrowd.it\/fr\/levaluation-pre-monetaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00e9valuation de l'entreprise<\/a> \u00e0 650 millions d'USD.<\/p>\n\n\n\n<p>En 2022, cependant, le vent a tourn\u00e9 : le succ\u00e8s de Substack ne s'est pas arr\u00eat\u00e9, mais le monde qui l'entoure a pris des directions compliqu\u00e9es et critiques qui ont mis fin \u00e0 la p\u00e9riode de valorisations astronomiques et de financements g\u00e9n\u00e9reux qu'ont connue les start-ups au cours des dix ann\u00e9es pr\u00e9c\u00e9dentes, et en particulier dans le climat d'optimisme post-pand\u00e9mique.<\/p>\n\n\n\n<p>C'est pourquoi un nouveau tour de table a \u00e9chou\u00e9 en 2022 : les investisseurs potentiels se sont montr\u00e9s prudents et m\u00e9fiants et Substack a cl\u00f4tur\u00e9 le tour de table pr\u00e9matur\u00e9ment.<\/p>\n\n\n\n<p class=\"translation-block\">L'entreprise d\u00e9cide donc de changer de strat\u00e9gie : elle cherche \u00e0 augmenter les revenus des abonnements, r\u00e9duit ses co\u00fbts et pr\u00e9pare une lev\u00e9e de fonds par crowdfunding.<\/p>\n\n\n\n<div data-aos= \"slide-right\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-block-1e0fbaf5 alignfull uagb-is-root-container\">\n<div style=\"margin-top:0;margin-bottom:0;height:8px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-bcf26494\"><h2 class=\"uagb-heading-text\"><strong>Vous souhaitez discuter directement avec nos experts en crowdfunding du sujet que vous lisez ?<\/strong><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-1263b640\"><p class=\"uagb-heading-text\">Turbo Crowd peut vous r\u00e9v\u00e9ler toutes les ficelles du m\u00e9tier de crowdfunding, vous montrer les possibilit\u00e9s de collecte de capitaux qui s'offrent \u00e0 vous et vous fournir un soutien pratique pour mettre en place une campagne de crowdfunding r\u00e9ussie.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__medium-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-66b0de0d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-adaecfd1 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/www.turbocrowd.it\/fr\/reserver-une-consultation-gratuite-sur-le-blog\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">R\u00e9servez un appel vid\u00e9o GRATUIT !<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pourquoi le crowdfunding ?<\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>Substack est un r\u00e9seau d'\u00e9crivains et de lecteurs qui gagnent de l'argent gr\u00e2ce \u00e0 leurs auteurs. Les lecteurs soutiennent par leurs abonnements uniquement les \u00e9crivains qu'ils pr\u00e9f\u00e8rent, avec lesquels se cr\u00e9e une relation de fid\u00e9lit\u00e9 quasi personnelle.<\/p>\n\n\n\n<p class=\"translation-block\">L'id\u00e9e est de <strong>construire une communaut\u00e9 et un nouveau mod\u00e8le d'entreprise<\/strong> et d'information avec les \u00e9crivains : c'est ce que souligne<a href=\"https:\/\/on.substack.com\/p\/wefunder\" target=\"_blank\" rel=\"noreferrer noopener\"> l'annonce de la campagne d'equity crowdfunding<\/a> publi\u00e9e par l'entreprise.<\/p>\n\n\n\n<p>L'equity crowdfunding repr\u00e9sente un autre moyen pour les auteurs de participer \u00e0 la croissance et aux b\u00e9n\u00e9fices de Substack : les investisseurs du crowdfunding deviennent des investisseurs parce qu'ils partagent un int\u00e9r\u00eat avec l'entreprise, et les producteurs de contenu de Substack refl\u00e8tent pleinement cet int\u00e9r\u00eat.<\/p>\n\n\n\n<p>En s'adressant directement \u00e0 ses cr\u00e9ateurs de contenu, la plateforme fait appel \u00e0 un public d\u00e9j\u00e0 engag\u00e9 qui a tout \u00e0 gagner de la croissance de l'entreprise et qui peut apporter une valeur significative (pas seulement \u00e9conomique) au projet.<\/p>\n\n\n\n<p>Enfin et surtout, l'equity crowdfunding est plus accessible que d'autres sources de financement, y compris le capital-risque lui-m\u00eame, parce qu'il exige moins de param\u00e8tres et de garanties. Ceci est particuli\u00e8rement pertinent pour Substack, qui, lors du ralentissement \u00e9conomique mondial, a d\u00fb faire face \u00e0 la prudence et \u00e0 la m\u00e9fiance du monde des investisseurs professionnels et a d\u00fb r\u00e9duire son \u00e9valuation d'environ 10% par rapport \u00e0 2021.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La strat\u00e9gie marketing de Substack<\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"translation-block\">La strat\u00e9gie de marketing de Substack pour l'equity crowdfunding<\/strong> repose sur quelques piliers :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>objectif pr\u00e9cis<\/li>\n\n\n\n<li>communication directe<\/li>\n\n\n\n<li>l'implication personnelle<\/li>\n\n\n\n<li>id\u00e9al \u00e9thique<\/li>\n\n\n\n<li>transparence.<\/li>\n<\/ul>\n\n\n\n<p>Tout d'abord, la plateforme a identifi\u00e9 un public cible tr\u00e8s sp\u00e9cifique d'investisseurs potentiels : les cr\u00e9ateurs de contenu inscrits sur la plateforme ou int\u00e9ress\u00e9s par celle-ci pour leur travail. La cible secondaire \u00e9tait les lecteurs ou, plus g\u00e9n\u00e9ralement, les utilisateurs de leur contenu.<\/p>\n\n\n\n<p>C'est de l\u00e0 que sont n\u00e9s les principaux atouts de la campagne :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>base de donn\u00e9es de contacts d\u00e9j\u00e0 disponible<\/li>\n\n\n\n<li>partager les objectifs avec les investisseurs potentiels.<\/li>\n<\/ul>\n\n\n\n<p class=\"translation-block\">Pour tirer parti de ces atouts, Substack a \u00e9labor\u00e9 une solide strat\u00e9gie de \"storytelling\" visant \u00e0 transmettre \u00e0 son r\u00e9seau les id\u00e9aux cl\u00e9s qui en font une communaut\u00e9 forte : la cr\u00e9ation de valeur partag\u00e9e, la libert\u00e9 d'expression, le \"pouvoir du peuple\", la d\u00e9mocratisation de la culture et la juste r\u00e9mun\u00e9ration du travail.<\/p>\n\n\n\n<p>La communication de Substack a \u00e9t\u00e9 tr\u00e8s insistante sur ces questions, pour contrebalancer les critiques qui voient dans son mod\u00e8le \u00e9conomique un risque de propagation d'id\u00e9es dangereuses et de \"fake news\", \u00e9tant donn\u00e9 le peu ou l'absence de contr\u00f4le de la plateforme sur les contenus.<\/p>\n\n\n\n<p class=\"translation-block\">Les canaux de communication les plus utilis\u00e9s \u00e9taient principalement ceux o\u00f9 le public cible se trouvait d\u00e9j\u00e0, c'est-\u00e0-dire la lettre d'information destin\u00e9e aux abonn\u00e9s de la plateforme et le blog interne. Cela a notamment permis d'\u00e9conomiser sur le budget m\u00e9dia. Mais Substack a \u00e9galement agi de mani\u00e8re plus cibl\u00e9e : elle a impliqu\u00e9 en premier lieu et personnellement les auteurs les plus populaires de la plateforme, s'assurant ainsi de leur soutien et, partant, d'un puissant bouche-\u00e0-oreille. Les auteurs ont en effet commenc\u00e9 \u00e0 parler de la campagne d'equity crowdfunding<\/strong> dans leur contenu, ce qui a donn\u00e9 une grande r\u00e9sonance au sujet et a attir\u00e9 les lecteurs vers le projet.<\/p>\n\n\n\n<p>Enfin, la soci\u00e9t\u00e9 a pris soin de souligner \u00e0 plusieurs reprises le risque de l'op\u00e9ration pour un investisseur, en recommandant de ne pas investir si l'on n'est pas en mesure de perdre la totalit\u00e9 de son capital sans cons\u00e9quences graves : une astuce qui est \u00e0 la fois une conformit\u00e9 r\u00e9glementaire et une d\u00e9monstration de transparence vis-\u00e0-vis des supporters (comme pour dire \"nous sommes du m\u00eame c\u00f4t\u00e9\").<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Equity crowdfunding Substack : r\u00e9sultats<\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>La <strong>Campagne de crowdfunding Substack<\/strong> a eu lieu sur la plateforme WeFunder entre la fin mars et la fin avril 2023.<\/p>\n\n\n\n<p class=\"translation-block\"><strong>Objectif<\/strong> : 2 millions de dollars, port\u00e9s \u00e0 5 millions de dollars apr\u00e8s le succ\u00e8s initial retentissant de la campagne.<\/p>\n\n\n\n<p class=\"translation-block\"><strong>Collection<\/strong> : 7,8 millions de dollars<\/p>\n\n\n\n<p><strong>Total des investisseurs<\/strong>: 6.688<\/p>\n\n\n\n<p class=\"translation-block\"><strong>Investissement moyen<\/strong> : 250<\/p>\n\n\n\n<p>Pour Substack, la campagne d'equity crowdfunding \u00e9tait la continuation d'une voie de financement qui, compar\u00e9e aux op\u00e9rations de capital-risque, \u00e9tait tr\u00e8s petite en taille, mais d'autant plus pertinente qu'elle \u00e9tait le r\u00e9sultat de l'implication d'investisseurs priv\u00e9s. Les fondateurs de l'entreprise ont d'ailleurs soulign\u00e9 que la v\u00e9ritable valeur ajout\u00e9e de la campagne d'equity crowdfunding - qu'ils ont appel\u00e9e Community Round - est l'acc\u00e8s aux commentaires des r\u00e9dacteurs et des lecteurs de la plateforme, qui sont pr\u00e9cieux et importants pour l'avenir du service.<\/p>\n\n\n\n<p><strong>Turbo Crowd a fait de l'engagement avec les clients ou les clients potentiels des entreprises une pierre angulaire de ses services de conseil en marketing du crowdfunding, et des \u00e9tudes de cas comme celle-ci en d\u00e9montrent la valeur. <\/strong><a href=\"https:\/\/www.turbocrowd.it\/fr\/crowdfunding-investisseur-client\/\" rel=\"noreferrer noopener\"><strong>les clients ou les clients potentiels <\/strong><\/a><strong>de soci\u00e9t\u00e9s est un pilier de son service de conseil en marketing de crowdfunding, et des \u00e9tudes de cas telles que celle-ci en d\u00e9montrent la valeur. <\/strong><\/p>\n\n\n\n<div data-aos= \"slide-right\" data-aos-duration=\"400\" data-aos-delay=\"0\" data-aos-easing=\"ease\" data-aos-once=\"true\" class=\"wp-block-uagb-container uagb-block-1e0fbaf5 alignfull uagb-is-root-container\">\n<div style=\"margin-top:0;margin-bottom:0;height:8px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-bcf26494\"><h2 class=\"uagb-heading-text\"><strong><strong><strong><strong>Vous avez besoin d'aide pour pr\u00e9parer une campagne de crowdfunding r\u00e9ussie et rechercher des investisseurs potentiels pour votre projet ?<\/strong><\/strong><\/strong><\/strong><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-1263b640\"><p class=\"uagb-heading-text\">Turbo Crowd peut vous accompagner tout au long du processus, de l'organisation de la pr\u00e9-foule \u00e0 la cl\u00f4ture de la collecte, en d\u00e9veloppant des strat\u00e9gies de marketing efficaces et innovantes pour promouvoir votre campagne de la meilleure fa\u00e7on possible.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__medium-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-66b0de0d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-adaecfd1 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/www.turbocrowd.it\/fr\/reserver-une-consultation-gratuite-sur-le-blog\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">R\u00e9servez un appel vid\u00e9o GRATUIT !<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Substack est une plateforme am\u00e9ricaine qui offre aux entreprises et aux journalistes la possibilit\u00e9 de publier gratuitement des lettres d'information et d'autres contenus, en gagnant de l'argent gr\u00e2ce aux abonnements des lecteurs. <\/p>","protected":false},"author":16,"featured_media":8358,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[332],"tags":[338,99,38],"class_list":["post-8356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-storie-casi-studio-crowdfunding","tag-casi-studio-crowdfunding","tag-crowdfunding-esempi","tag-strategie-di-marketing"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Storie di successo: caso studio crowdfunding di Substack | Turbo Crowd<\/title>\n<meta name=\"description\" content=\"Substack \u00e8 una piattaforma per la creazione di contenuti e la remunerazione dei creatori tramite abbonamenti: nel 2023 ha fatto una campagna equity crowdfunding.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.turbocrowd.it\/fr\/crowdfunding-substack-etude-de-cas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Storie di successo: caso studio crowdfunding di Substack | Turbo Crowd\" \/>\n<meta property=\"og:description\" content=\"Substack \u00e8 una piattaforma per la creazione di contenuti e la remunerazione dei creatori tramite abbonamenti: nel 2023 ha fatto una campagna equity crowdfunding.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.turbocrowd.it\/fr\/crowdfunding-substack-etude-de-cas\/\" \/>\n<meta property=\"og:site_name\" content=\"Turbo Crowd\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063968918578\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-06T17:31:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-22T10:38:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesca Bello\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesca Bello\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/\"},\"author\":{\"name\":\"Francesca Bello\",\"@id\":\"https:\/\/www.turbocrowd.it\/fr\/#\/schema\/person\/c504882b6fa8fac7254de2625e1743e2\"},\"headline\":\"Storie di successo: caso studio crowdfunding di Substack\",\"datePublished\":\"2024-03-06T17:31:32+00:00\",\"dateModified\":\"2025-05-22T10:38:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/\"},\"wordCount\":1167,\"publisher\":{\"@id\":\"https:\/\/www.turbocrowd.it\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280.jpg\",\"keywords\":[\"casi studio crowdfunding\",\"crowdfunding esempi\",\"strategie di marketing\"],\"articleSection\":[\"Casi Studio Crowdfunding\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/\",\"url\":\"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/\",\"name\":\"Storie di successo: caso studio crowdfunding di Substack | Turbo Crowd\",\"isPartOf\":{\"@id\":\"https:\/\/www.turbocrowd.it\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280.jpg\",\"datePublished\":\"2024-03-06T17:31:32+00:00\",\"dateModified\":\"2025-05-22T10:38:21+00:00\",\"description\":\"Substack \u00e8 una piattaforma per la creazione di contenuti e la remunerazione dei creatori tramite abbonamenti: nel 2023 ha fatto una campagna equity crowdfunding.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/#primaryimage\",\"url\":\"https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280.jpg\",\"contentUrl\":\"https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280.jpg\",\"width\":1280,\"height\":853,\"caption\":\"substack crowdfunding\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.turbocrowd.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Storie di successo: caso studio crowdfunding di Substack\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.turbocrowd.it\/fr\/#website\",\"url\":\"https:\/\/www.turbocrowd.it\/fr\/\",\"name\":\"Turbo Crowd\",\"description\":\"Consulenza marketing per campagne crowdfunding\",\"publisher\":{\"@id\":\"https:\/\/www.turbocrowd.it\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.turbocrowd.it\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.turbocrowd.it\/fr\/#organization\",\"name\":\"Turbo Crowd\",\"url\":\"https:\/\/www.turbocrowd.it\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.turbocrowd.it\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2019\/12\/cropped-Logo-turbo-crowd-quadrato-1.png\",\"contentUrl\":\"https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2019\/12\/cropped-Logo-turbo-crowd-quadrato-1.png\",\"width\":512,\"height\":512,\"caption\":\"Turbo Crowd\"},\"image\":{\"@id\":\"https:\/\/www.turbocrowd.it\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063968918578\",\"https:\/\/www.linkedin.com\/company\/turbo-crowd\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.turbocrowd.it\/fr\/#\/schema\/person\/c504882b6fa8fac7254de2625e1743e2\",\"name\":\"Francesca Bello\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.turbocrowd.it\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/936a8f8e46f5f254bfb32ed8b6f0e38167ff069ca0e815be0c26982a3096a33e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/936a8f8e46f5f254bfb32ed8b6f0e38167ff069ca0e815be0c26982a3096a33e?s=96&d=mm&r=g\",\"caption\":\"Francesca Bello\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Success stories : Substack | Turbo Crowd \u00e9tude de cas de crowdfunding","description":"Substack est une plateforme de cr\u00e9ation de contenu et de r\u00e9mun\u00e9ration des cr\u00e9ateurs par le biais d'abonnements : en 2023, elle a men\u00e9 une campagne d'equity crowdfunding.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.turbocrowd.it\/fr\/crowdfunding-substack-etude-de-cas\/","og_locale":"fr_FR","og_type":"article","og_title":"Storie di successo: caso studio crowdfunding di Substack | Turbo Crowd","og_description":"Substack \u00e8 una piattaforma per la creazione di contenuti e la remunerazione dei creatori tramite abbonamenti: nel 2023 ha fatto una campagna equity crowdfunding.","og_url":"https:\/\/www.turbocrowd.it\/fr\/crowdfunding-substack-etude-de-cas\/","og_site_name":"Turbo Crowd","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063968918578","article_published_time":"2024-03-06T17:31:32+00:00","article_modified_time":"2025-05-22T10:38:21+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280.jpg","type":"image\/jpeg"}],"author":"Francesca Bello","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Francesca Bello","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/#article","isPartOf":{"@id":"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/"},"author":{"name":"Francesca Bello","@id":"https:\/\/www.turbocrowd.it\/fr\/#\/schema\/person\/c504882b6fa8fac7254de2625e1743e2"},"headline":"Storie di successo: caso studio crowdfunding di Substack","datePublished":"2024-03-06T17:31:32+00:00","dateModified":"2025-05-22T10:38:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/"},"wordCount":1167,"publisher":{"@id":"https:\/\/www.turbocrowd.it\/fr\/#organization"},"image":{"@id":"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/#primaryimage"},"thumbnailUrl":"https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280.jpg","keywords":["casi studio crowdfunding","crowdfunding esempi","strategie di marketing"],"articleSection":["Casi Studio Crowdfunding"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/","url":"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/","name":"Success stories : Substack | Turbo Crowd \u00e9tude de cas de crowdfunding","isPartOf":{"@id":"https:\/\/www.turbocrowd.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/#primaryimage"},"image":{"@id":"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/#primaryimage"},"thumbnailUrl":"https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280.jpg","datePublished":"2024-03-06T17:31:32+00:00","dateModified":"2025-05-22T10:38:21+00:00","description":"Substack est une plateforme de cr\u00e9ation de contenu et de r\u00e9mun\u00e9ration des cr\u00e9ateurs par le biais d'abonnements : en 2023, elle a men\u00e9 une campagne d'equity crowdfunding.","breadcrumb":{"@id":"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/#primaryimage","url":"https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280.jpg","contentUrl":"https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280.jpg","width":1280,"height":853,"caption":"substack crowdfunding"},{"@type":"BreadcrumbList","@id":"https:\/\/www.turbocrowd.it\/caso-studio-crowdfunding-substack\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.turbocrowd.it\/"},{"@type":"ListItem","position":2,"name":"Storie di successo: caso studio crowdfunding di Substack"}]},{"@type":"WebSite","@id":"https:\/\/www.turbocrowd.it\/fr\/#website","url":"https:\/\/www.turbocrowd.it\/fr\/","name":"Foule turbo","description":"Conseil en marketing pour les campagnes de crowdfunding","publisher":{"@id":"https:\/\/www.turbocrowd.it\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.turbocrowd.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.turbocrowd.it\/fr\/#organization","name":"Foule turbo","url":"https:\/\/www.turbocrowd.it\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.turbocrowd.it\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2019\/12\/cropped-Logo-turbo-crowd-quadrato-1.png","contentUrl":"https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2019\/12\/cropped-Logo-turbo-crowd-quadrato-1.png","width":512,"height":512,"caption":"Turbo Crowd"},"image":{"@id":"https:\/\/www.turbocrowd.it\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063968918578","https:\/\/www.linkedin.com\/company\/turbo-crowd\/"]},{"@type":"Person","@id":"https:\/\/www.turbocrowd.it\/fr\/#\/schema\/person\/c504882b6fa8fac7254de2625e1743e2","name":"Francesca Bello","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.turbocrowd.it\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/936a8f8e46f5f254bfb32ed8b6f0e38167ff069ca0e815be0c26982a3096a33e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/936a8f8e46f5f254bfb32ed8b6f0e38167ff069ca0e815be0c26982a3096a33e?s=96&d=mm&r=g","caption":"Francesca Bello"}}]}},"uagb_featured_image_src":{"full":["https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280.jpg",1280,853,false],"thumbnail":["https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280-150x150.jpg",150,150,true],"medium":["https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280-768x512.jpg",768,512,true],"large":["https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280-1024x682.jpg",1024,682,true],"1536x1536":["https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280.jpg",1280,853,false],"2048x2048":["https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280.jpg",1280,853,false],"trp-custom-language-flag":["https:\/\/www.turbocrowd.it\/wp-content\/uploads\/2024\/03\/man-791049_1280-18x12.jpg",18,12,true]},"uagb_author_info":{"display_name":"Francesca Bello","author_link":"https:\/\/www.turbocrowd.it\/fr\/author\/fbelloturbocrowd-it\/"},"uagb_comment_info":0,"uagb_excerpt":"Substack \u00e8 una piattaforma americana che offre ad aziende e giornalisti la possibilit\u00e0 di pubblicare newsletter e altri contenuti gratuitamente, guadagnando sugli abbonamenti dei lettori.","_links":{"self":[{"href":"https:\/\/www.turbocrowd.it\/fr\/wp-json\/wp\/v2\/posts\/8356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.turbocrowd.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.turbocrowd.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.turbocrowd.it\/fr\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.turbocrowd.it\/fr\/wp-json\/wp\/v2\/comments?post=8356"}],"version-history":[{"count":6,"href":"https:\/\/www.turbocrowd.it\/fr\/wp-json\/wp\/v2\/posts\/8356\/revisions"}],"predecessor-version":[{"id":9784,"href":"https:\/\/www.turbocrowd.it\/fr\/wp-json\/wp\/v2\/posts\/8356\/revisions\/9784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.turbocrowd.it\/fr\/wp-json\/wp\/v2\/media\/8358"}],"wp:attachment":[{"href":"https:\/\/www.turbocrowd.it\/fr\/wp-json\/wp\/v2\/media?parent=8356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.turbocrowd.it\/fr\/wp-json\/wp\/v2\/categories?post=8356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.turbocrowd.it\/fr\/wp-json\/wp\/v2\/tags?post=8356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}